{"id":5399,"date":"2026-09-01T19:57:46","date_gmt":"2026-09-01T22:57:46","guid":{"rendered":"https:\/\/icbneuro.com.br\/portal\/?p=5399"},"modified":"2026-09-01T19:57:46","modified_gmt":"2026-09-01T22:57:46","slug":"envelhecimento-mais-lento-dos-orgaos-e-mais-comum-entre-aqueles-que-dormem-de-seis-a-oito-horas","status":"publish","type":"post","link":"https:\/\/icbneuro.com.br\/portal\/envelhecimento-mais-lento-dos-orgaos-e-mais-comum-entre-aqueles-que-dormem-de-seis-a-oito-horas\/","title":{"rendered":"Envelhecimento mais lento dos \u00f3rg\u00e3os \u00e9 mais comum entre aqueles que dormem de seis a oito horas"},"content":{"rendered":"<div id=\"m_4422705779587974637yui_3_16_0_ym19_1_1511348855948_49464\">\n<div dir=\"ltr\">\n<div id=\"m_-1278217216785674693ydp9dc2daf3yiv0291208248yMail_cursorElementTracker_1606865733683\" dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">Pesquisa na Nature associa faixa ideal de sono a menor envelhecimento de 23 \u00f3rg\u00e3os.<br \/>\n<!--more--><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div id=\"m_4422705779587974637yui_3_16_0_ym19_1_1511348855948_49464\">\n<div dir=\"ltr\">\n<div id=\"m_-1278217216785674693ydp9dc2daf3yiv0291208248yMail_cursorElementTracker_1606865733683\" dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<hr \/>\n<p dir=\"ltr\">A an\u00e1lise do envelhecimento de 23 diferentes \u00f3rg\u00e3os do corpo aponta que ele \u00e9 menor entre indiv\u00edduos que dormem entre 6.4 e 7.8 horas por noite.\u00a0Menos ou mais sono do que isso est\u00e1 associado\u00a0a um envelhecimento mais r\u00e1pido do c\u00e9rebro, cora\u00e7\u00e3o, pulm\u00f5es, sistema imunol\u00f3gico, entre outros \u00f3rg\u00e3os, al\u00e9m de uma s\u00e9rie de doen\u00e7as. Esses s\u00e3o resultados de uma pesquisa conduzida pela Universidade de Columbia nos EUA, envolvendo cerca de meio milh\u00e3o de indiv\u00edduos, e publicada recentemente pela prestigiada revista Nature.<\/p>\n<p class=\"texto\">O padr\u00e3o de envelhecimento foi feito atrav\u00e9s de marcadores, como prote\u00ednas e outras mol\u00e9culas menores associadas a determinados \u00f3rg\u00e3os, al\u00e9m da estrutura desses \u00f3rg\u00e3os por imagens m\u00e9dicas. Os pesquisadores alertam para que esses achados n\u00e3o sejam interpretados como se dormir menos de seis ou mais de oito horas fosse provocar um envelhecimento mais r\u00e1pido, mas \u00e9 prov\u00e1vel que dormir fora dessa faixa \u00f3tima pode ser um sinal de uma m\u00e1 condi\u00e7\u00e3o de sa\u00fade do corpo como um todo.<\/p>\n<p class=\"texto\">Vale lembrar que o n\u00famero ideal de horas de sono \u00e9 aquele que faz com que a pessoa no outro dia sinta que dormiu o suficiente.\u00a0Um percentual pequeno de pessoas sente-se\u00a0bem com menos de sete horas, e estes s\u00e3o chamados de dormidores curtos. H\u00e1 tamb\u00e9m os dormidores longos, aqueles que precisam de mais de oito horas de sono e que tamb\u00e9m representam uma minoria. Por\u00e9m, a maior parte da popula\u00e7\u00e3o dorme entre sete e oito horas por noite.<\/p>\n<p>* <strong>Ricardo Afonso Teixeira \u00e9 doutor em neurologia pela Unicamp e neurologista do Instituto do C\u00e9rebro de Bras\u00edlia.<br \/>\n<\/strong><strong>Cr\u00e9dito foto:<\/strong> Pexels<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><!-- \/wp:paragraph --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pesquisa na Nature associa faixa ideal de sono a menor envelhecimento de 23 \u00f3rg\u00e3os.<\/p>\n","protected":false},"author":1,"featured_media":5400,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[]},"categories":[57,52],"tags":[],"_links":{"self":[{"href":"https:\/\/icbneuro.com.br\/portal\/wp-json\/wp\/v2\/posts\/5399"}],"collection":[{"href":"https:\/\/icbneuro.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/icbneuro.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/icbneuro.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/icbneuro.com.br\/portal\/wp-json\/wp\/v2\/comments?post=5399"}],"version-history":[{"count":1,"href":"https:\/\/icbneuro.com.br\/portal\/wp-json\/wp\/v2\/posts\/5399\/revisions"}],"predecessor-version":[{"id":5401,"href":"https:\/\/icbneuro.com.br\/portal\/wp-json\/wp\/v2\/posts\/5399\/revisions\/5401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/icbneuro.com.br\/portal\/wp-json\/wp\/v2\/media\/5400"}],"wp:attachment":[{"href":"https:\/\/icbneuro.com.br\/portal\/wp-json\/wp\/v2\/media?parent=5399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/icbneuro.com.br\/portal\/wp-json\/wp\/v2\/categories?post=5399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/icbneuro.com.br\/portal\/wp-json\/wp\/v2\/tags?post=5399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}